{"id":28,"count":1,"description":"","link":"https:\/\/museum-reviews.jenspot.com\/index.php\/category\/museum\/birmingham-museum\/","name":"Birmingham","slug":"birmingham-museum","taxonomy":"category","parent":10,"meta":[],"_links":{"self":[{"href":"https:\/\/museum-reviews.jenspot.com\/index.php\/wp-json\/wp\/v2\/categories\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museum-reviews.jenspot.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/museum-reviews.jenspot.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/museum-reviews.jenspot.com\/index.php\/wp-json\/wp\/v2\/categories\/10"}],"wp:post_type":[{"href":"https:\/\/museum-reviews.jenspot.com\/index.php\/wp-json\/wp\/v2\/posts?categories=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}